{"id":4452,"date":"2018-08-29T17:53:55","date_gmt":"2018-08-29T10:53:55","guid":{"rendered":"https:\/\/kiji.life\/eats\/?post_type=restaurant&#038;p=4452"},"modified":"2018-08-29T18:06:23","modified_gmt":"2018-08-29T11:06:23","slug":"joshoken","status":"publish","type":"restaurant","link":"https:\/\/kiji.life\/eats\/restaurant\/joshoken\/","title":{"rendered":"Joshoken"},"content":{"rendered":"<h2>Joshoken \u0e01\u0e2d\u0e07\u0e17\u0e31\u0e1e\u0e23\u0e32\u0e40\u0e21\u0e19\u0e1c\u0e39\u0e49\u0e41\u0e02\u0e47\u0e07\u0e41\u0e01\u0e23\u0e48\u0e07<\/h2>\n<p><span style=\"font-weight: 400;\">\u0e23\u0e49\u0e32\u0e19\u0e23\u0e32\u0e40\u0e21\u0e19\u0e08\u0e32\u0e01\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e0a\u0e34\u0e1a\u0e30\u0e17\u0e35\u0e48\u0e44\u0e1b\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e0a\u0e37\u0e48\u0e2d\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e42\u0e14\u0e48\u0e07\u0e14\u0e31\u0e07\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e2a\u0e34\u0e07\u0e04\u0e42\u0e1b\u0e23\u0e4c \u0e08\u0e19\u0e02\u0e22\u0e32\u0e22\u0e2a\u0e32\u0e02\u0e32\u0e43\u0e19\u0e2d\u0e35\u0e01\u0e2b\u0e25\u0e32\u0e22\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2a\u0e32\u0e02\u0e32\u0e43\u0e19\u0e44\u0e17\u0e22\u0e40\u0e1e\u0e34\u0e48\u0e07\u0e08\u0e30\u0e42\u0e22\u0e01\u0e22\u0e49\u0e32\u0e22\u0e08\u0e32\u0e01\u0e43\u0e19\u0e0b\u0e2d\u0e22\u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 49 \u0e21\u0e32\u0e2d\u0e22\u0e39\u0e48\u0e17\u0e35\u0e48\u0e15\u0e31\u0e49\u0e07\u0e41\u0e2b\u0e48\u0e07\u0e43\u0e2b\u0e21\u0e48\u0e43\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 Nihonmura Mall \u0e0b\u0e36\u0e48\u0e07\u0e43\u0e0a\u0e49\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e40\u0e14\u0e35\u0e22\u0e27\u0e01\u0e31\u0e19\u0e01\u0e31\u0e1a\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e0d\u0e35\u0e48\u0e1b\u0e38\u0e48\u0e19 Uomasa (\u0e2d\u0e35\u0e01\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e0d\u0e35\u0e48\u0e1b\u0e38\u0e48\u0e19\u0e40\u0e01\u0e48\u0e32\u0e41\u0e01\u0e48\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e41\u0e19\u0e48\u0e19\u0e2d\u0e19\u0e27\u0e48\u0e32\u0e19\u0e31\u0e48\u0e19\u0e08\u0e36\u0e07\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e23\u0e49\u0e32\u0e19 <strong>Joshoken<\/strong> \u0e41\u0e2b\u0e48\u0e07\u0e19\u0e35\u0e49 \u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e21\u0e35\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e41\u0e04\u0e48\u0e23\u0e32\u0e40\u0e21\u0e19\u0e40\u0e17\u0e48\u0e32\u0e19\u0e31\u0e49\u0e19 \u0e2b\u0e32\u0e01\u0e41\u0e15\u0e48\u0e40\u0e23\u0e35\u0e22\u0e01\u0e27\u0e48\u0e32\u0e04\u0e23\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e0d\u0e35\u0e48\u0e1b\u0e38\u0e48\u0e19\u0e40\u0e25\u0e22\u0e01\u0e47\u0e27\u0e48\u0e32\u0e44\u0e14\u0e49\u00a0 <\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-4453 aligncenter\" src=\"https:\/\/kiji.life\/eats\/wp-content\/uploads\/2018\/08\/FCM_6700-copy-1024x683.jpg\" alt=\"\" width=\"1024\" height=\"683\" srcset=\"https:\/\/kiji.life\/eats\/wp-content\/uploads\/2018\/08\/FCM_6700-copy-1024x683.jpg 1024w, https:\/\/kiji.life\/eats\/wp-content\/uploads\/2018\/08\/FCM_6700-copy-300x200.jpg 300w, https:\/\/kiji.life\/eats\/wp-content\/uploads\/2018\/08\/FCM_6700-copy-768x512.jpg 768w, https:\/\/kiji.life\/eats\/wp-content\/uploads\/2018\/08\/FCM_6700-copy.jpg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p>\u0e27\u0e48\u0e32\u0e14\u0e49\u0e27\u0e22\u0e1a\u0e23\u0e23\u0e22\u0e32\u0e01\u0e32\u0e28\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e02\u0e2d\u0e07\u0e23\u0e49\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e23\u0e32\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e27\u0e48\u0e32\u0e2b\u0e25\u0e32\u0e22\u0e04\u0e19\u0e15\u0e49\u0e2d\u0e07\u0e0a\u0e2d\u0e1a\u0e41\u0e19\u0e48\u0e46 \u0e01\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e42\u0e14\u0e14\u0e40\u0e14\u0e48\u0e19\u0e08\u0e32\u0e01\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e44\u0e21\u0e49 \u0e17\u0e31\u0e49\u0e07\u0e44\u0e21\u0e49\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e41\u0e02\u0e47\u0e07 \u0e44\u0e21\u0e48\u0e44\u0e1c\u0e48 \u0e1c\u0e2a\u0e21\u0e1c\u0e2a\u0e32\u0e19\u0e01\u0e31\u0e1a\u0e07\u0e32\u0e19\u0e04\u0e2d\u0e19\u0e01\u0e23\u0e35\u0e15 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e1b\u0e23\u0e31\u0e1a\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e32\u0e21\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e25\u0e14\u0e2b\u0e25\u0e31\u0e48\u0e19\u0e01\u0e31\u0e19\u0e44\u0e1b \u0e0a\u0e31\u0e49\u0e19\u0e25\u0e48\u0e32\u0e07\u0e2a\u0e38\u0e14\u0e40\u0e1b\u0e47\u0e19\u0e0a\u0e38\u0e14\u0e42\u0e15\u0e4a\u0e30\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e17\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e1a\u0e1a\u0e1b\u0e01\u0e15\u0e34 \u0e2a\u0e48\u0e27\u0e19\u0e17\u0e35\u0e48\u0e2a\u0e2d\u0e07\u0e17\u0e33\u0e01\u0e32\u0e23\u0e22\u0e01\u0e1e\u0e37\u0e49\u0e19\u0e2a\u0e39\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e42\u0e15\u0e4a\u0e30\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e17\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e19\u0e31\u0e48\u0e07\u0e1e\u0e37\u0e49\u0e19\u0e2b\u0e49\u0e2d\u0e22\u0e04\u0e32\u0e2a\u0e44\u0e15\u0e25\u0e4c\u0e0d\u0e35\u0e48\u0e1b\u0e38\u0e48\u0e19 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e1a\u0e31\u0e19\u0e44\u0e14\u0e40\u0e25\u0e47\u0e01\u0e46 \u0e44\u0e1b\u0e2a\u0e39\u0e48\u0e0a\u0e31\u0e49\u0e19\u0e25\u0e2d\u0e22 \u0e17\u0e35\u0e48\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e1b\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e49\u0e2d\u0e07\u0e2a\u0e31\u0e07\u0e2a\u0e23\u0e23\u0e04\u0e4c\u0e41\u0e1a\u0e1a\u0e2a\u0e48\u0e27\u0e19\u0e15\u0e31\u0e27\u0e44\u0e14\u0e49<\/p>\n<p><span style=\"font-weight: 400;\">\u0e27\u0e01\u0e01\u0e25\u0e31\u0e1a\u0e40\u0e02\u0e49\u0e32\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e23\u0e32\u0e40\u0e21\u0e19 \u0e40\u0e23\u0e32\u0e02\u0e2d\u0e41\u0e19\u0e30\u0e19\u0e33 <b>Shio Ramen\u00a0<\/b><\/span><span style=\"font-weight: 400;\">\u0e23\u0e32\u0e40\u0e21\u0e19\u0e23\u0e2a\u0e40\u0e01\u0e25\u0e37\u0e2d\u0e17\u0e35\u0e48\u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e40\u0e04\u0e47\u0e21\u0e19\u0e34\u0e14\u0e46 \u0e01\u0e33\u0e25\u0e31\u0e07\u0e14\u0e35 \u0e19\u0e49\u0e33\u0e0b\u0e38\u0e1b\u0e41\u0e21\u0e49\u0e08\u0e30\u0e14\u0e39\u0e43\u0e2a\u0e41\u0e15\u0e48\u0e01\u0e25\u0e31\u0e1a\u0e43\u0e2b\u0e49\u0e23\u0e2a\u0e40\u0e02\u0e49\u0e21\u0e02\u0e49\u0e19\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e25\u0e34\u0e48\u0e19\u0e2b\u0e2d\u0e21\u0e40\u0e2d\u0e32\u0e21\u0e32\u0e01\u0e46 \u0e17\u0e32\u0e07\u0e23\u0e49\u0e32\u0e19\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e43\u0e0a\u0e49\u0e40\u0e2a\u0e49\u0e19\u0e23\u0e32\u0e40\u0e21\u0e19\u0e02\u0e19\u0e32\u0e14\u0e40\u0e25\u0e47\u0e01\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32\u0e08\u0e32\u0e01\u0e0d\u0e35\u0e48\u0e1b\u0e38\u0e48\u0e19 \u0e25\u0e27\u0e01\u0e21\u0e32\u0e41\u0e1a\u0e1a\u0e19\u0e38\u0e48\u0e21\u0e44\u0e21\u0e48\u0e41\u0e02\u0e47\u0e07\u0e21\u0e32\u0e01\u0e19\u0e31\u0e01 \u0e42\u0e1b\u0e30\u0e14\u0e49\u0e27\u0e22\u0e2b\u0e21\u0e39\u0e0a\u0e32\u0e0a\u0e39\u0e15\u0e34\u0e14\u0e21\u0e31\u0e19 \u0e44\u0e02\u0e48\u0e15\u0e49\u0e21\u0e40\u0e15\u0e47\u0e21\u0e1f\u0e2d\u0e07 \u0e40\u0e2b\u0e47\u0e14\u0e2b\u0e39\u0e2b\u0e19\u0e39 \u0e41\u0e25\u0e30\u0e21\u0e30\u0e19\u0e32\u0e27\u0e1d\u0e32\u0e19\u0e1a\u0e32\u0e07\u0e46 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e23\u0e34\u0e01\u0e40\u0e1c\u0e32\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e23\u0e2a\u0e0a\u0e32\u0e15\u0e34<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-4454 aligncenter\" src=\"https:\/\/kiji.life\/eats\/wp-content\/uploads\/2018\/08\/FCM_6172-copy-1024x659.jpg\" alt=\"\" width=\"1024\" height=\"659\" srcset=\"https:\/\/kiji.life\/eats\/wp-content\/uploads\/2018\/08\/FCM_6172-copy-1024x659.jpg 1024w, https:\/\/kiji.life\/eats\/wp-content\/uploads\/2018\/08\/FCM_6172-copy-300x193.jpg 300w, https:\/\/kiji.life\/eats\/wp-content\/uploads\/2018\/08\/FCM_6172-copy-768x494.jpg 768w, https:\/\/kiji.life\/eats\/wp-content\/uploads\/2018\/08\/FCM_6172-copy.jpg 1279w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<h5 style=\"text-align: center;\"><em><b>Shio Ramen (180 \u0e1a\u0e32\u0e17)<\/b><\/em><\/h5>\n<p>\u0e0a\u0e32\u0e21\u0e15\u0e48\u0e2d\u0e44\u0e1b\u0e40\u0e2d\u0e32\u0e43\u0e08\u0e04\u0e19\u0e23\u0e31\u0e01\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e <strong>Tanmen<\/strong> \u0e23\u0e32\u0e40\u0e21\u0e19\u0e1c\u0e31\u0e01\u0e17\u0e35\u0e48\u0e14\u0e39\u0e41\u0e27\u0e4a\u0e1a\u0e41\u0e23\u0e01\u0e04\u0e25\u0e49\u0e32\u0e22\u0e46 \u0e23\u0e32\u0e14\u0e2b\u0e19\u0e49\u0e32\u0e2d\u0e22\u0e39\u0e48\u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e19\u0e01\u0e31\u0e19 \u0e2b\u0e2d\u0e21\u0e01\u0e25\u0e21\u0e01\u0e25\u0e48\u0e2d\u0e21\u0e14\u0e49\u0e27\u0e22\u0e19\u0e49\u0e33\u0e0b\u0e38\u0e1b\u0e42\u0e0a\u0e22\u0e38 \u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21\u0e14\u0e49\u0e27\u0e22\u0e01\u0e25\u0e34\u0e48\u0e19\u0e41\u0e25\u0e30\u0e23\u0e2a\u0e0a\u0e32\u0e15\u0e34\u0e08\u0e32\u0e01\u0e1c\u0e31\u0e01\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e2d\u0e22\u0e48\u0e32\u0e07 \u0e16\u0e31\u0e48\u0e27\u0e07\u0e2d\u0e01 \u0e01\u0e30\u0e2b\u0e25\u0e48\u0e33\u0e1b\u0e25\u0e35 \u0e41\u0e04\u0e23\u0e2d\u0e17 \u0e40\u0e2b\u0e47\u0e14\u0e2b\u0e39\u0e2b\u0e19\u0e39\u0e0b\u0e2d\u0e22 \u0e41\u0e25\u0e30\u0e1b\u0e34\u0e14\u0e17\u0e49\u0e32\u0e22\u0e14\u0e49\u0e27\u0e22\u0e2b\u0e21\u0e39\u0e2a\u0e32\u0e21\u0e0a\u0e31\u0e49\u0e19\u0e2d\u0e35\u0e01\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e0a\u0e34\u0e49\u0e19 \u0e15\u0e31\u0e27\u0e19\u0e49\u0e33\u0e0b\u0e38\u0e1b\u0e25\u0e31\u0e01\u0e29\u0e13\u0e30\u0e2b\u0e19\u0e37\u0e14\u0e46 \u0e04\u0e25\u0e49\u0e32\u0e22\u0e23\u0e32\u0e14\u0e2b\u0e19\u0e49\u0e32 \u0e41\u0e15\u0e48\u0e23\u0e2a\u0e0a\u0e32\u0e15\u0e34\u0e41\u0e15\u0e01\u0e15\u0e48\u0e32\u0e07\u0e01\u0e31\u0e19\u0e41\u0e19\u0e48\u0e19\u0e2d\u0e19<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-4455 aligncenter\" src=\"https:\/\/kiji.life\/eats\/wp-content\/uploads\/2018\/08\/FCM_6175-copy-1024x682.jpg\" alt=\"\" width=\"1024\" height=\"682\" srcset=\"https:\/\/kiji.life\/eats\/wp-content\/uploads\/2018\/08\/FCM_6175-copy-1024x682.jpg 1024w, https:\/\/kiji.life\/eats\/wp-content\/uploads\/2018\/08\/FCM_6175-copy-300x200.jpg 300w, https:\/\/kiji.life\/eats\/wp-content\/uploads\/2018\/08\/FCM_6175-copy-768x511.jpg 768w, https:\/\/kiji.life\/eats\/wp-content\/uploads\/2018\/08\/FCM_6175-copy.jpg 1281w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<h5 style=\"text-align: center;\"><em><strong>Tanmen (220 \u0e1a\u0e32\u0e17)<\/strong><\/em><\/h5>\n<p>\u0e40\u0e23\u0e35\u0e22\u0e01\u0e44\u0e14\u0e49\u0e27\u0e48\u0e32 Joshoken \u0e16\u0e37\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e2d\u0e35\u0e01\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e23\u0e49\u0e32\u0e19\u0e23\u0e32\u0e40\u0e21\u0e19\u0e17\u0e35\u0e48\u0e04\u0e38\u0e49\u0e21\u0e04\u0e48\u0e32 \u0e17\u0e31\u0e49\u0e07\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e02\u0e2d\u0e07\u0e04\u0e27\u0e32\u0e21\u0e2d\u0e23\u0e48\u0e2d\u0e22 \u0e1a\u0e23\u0e23\u0e22\u0e32\u0e01\u0e32\u0e28 \u0e41\u0e16\u0e21\u0e14\u0e49\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22\u0e02\u0e2d\u0e07\u0e40\u0e21\u0e19\u0e39\u0e17\u0e35\u0e48\u0e40\u0e23\u0e32\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e27\u0e48\u0e32\u0e19\u0e48\u0e32\u0e08\u0e30\u0e04\u0e23\u0e1a\u0e17\u0e38\u0e01\u0e04\u0e27\u0e32\u0e21\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e0d\u0e35\u0e48\u0e1b\u0e38\u0e48\u0e19 \u0e23\u0e27\u0e21\u0e44\u0e1b\u0e16\u0e36\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e01\u0e47\u0e21\u0e35\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e04\u0e23\u0e1a\u0e04\u0e23\u0e31\u0e19 \u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e38\u0e01\u0e01\u0e32\u0e23\u0e2a\u0e31\u0e07\u0e2a\u0e23\u0e23\u0e04\u0e4c\u0e44\u0e14\u0e49\u0e15\u0e25\u0e2d\u0e14\u0e17\u0e31\u0e49\u0e07\u0e04\u0e37\u0e19<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Joshoken \u0e01\u0e2d\u0e07\u0e17\u0e31\u0e1e\u0e23\u0e32\u0e40\u0e21\u0e19\u0e1c\u0e39\u0e49\u0e41\u0e02\u0e47\u0e07\u0e41\u0e01\u0e23\u0e48\u0e07 \u0e23\u0e49\u0e32\u0e19\u0e23\u0e32\u0e40\u0e21\u0e19\u0e08\u0e32\u0e01\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e0a\u0e34\u0e1a\u0e30\u0e17\u0e35\u0e48\u0e44\u0e1b\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e0a\u0e37\u0e48\u0e2d\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e42\u0e14\u0e48\u0e07\u0e14\u0e31\u0e07\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e2a\u0e34\u0e07\u0e04\u0e42\u0e1b\u0e23\u0e4c \u0e08\u0e19\u0e02\u0e22\u0e32\u0e22\u0e2a\u0e32\u0e02\u0e32\u0e43\u0e19\u0e2d\u0e35\u0e01\u0e2b\u0e25\u0e32\u0e22\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2a\u0e32\u0e02\u0e32\u0e43\u0e19\u0e44\u0e17\u0e22\u0e40\u0e1e\u0e34\u0e48\u0e07\u0e08\u0e30\u0e42\u0e22\u0e01\u0e22\u0e49\u0e32\u0e22\u0e08\u0e32\u0e01\u0e43\u0e19\u0e0b\u0e2d\u0e22\u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 49 \u0e21\u0e32\u0e2d\u0e22\u0e39\u0e48\u0e17\u0e35\u0e48\u0e15\u0e31\u0e49\u0e07\u0e41\u0e2b\u0e48\u0e07\u0e43\u0e2b\u0e21\u0e48\u0e43\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 Nihonmura Mall \u0e0b\u0e36\u0e48\u0e07\u0e43\u0e0a\u0e49\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e40\u0e14\u0e35\u0e22\u0e27\u0e01\u0e31\u0e19\u0e01\u0e31\u0e1a\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e0d\u0e35\u0e48\u0e1b\u0e38\u0e48\u0e19 Uomasa (\u0e2d\u0e35\u0e01\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e0d\u0e35\u0e48\u0e1b\u0e38\u0e48\u0e19\u0e40\u0e01\u0e48\u0e32\u0e41\u0e01\u0e48\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e41\u0e19\u0e48\u0e19\u0e2d\u0e19\u0e27\u0e48\u0e32\u0e19\u0e31\u0e48\u0e19\u0e08\u0e36\u0e07\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e23\u0e49\u0e32\u0e19 Joshoken \u0e41\u0e2b\u0e48\u0e07\u0e19\u0e35\u0e49 \u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e21\u0e35\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e41\u0e04\u0e48\u0e23\u0e32\u0e40\u0e21\u0e19\u0e40\u0e17\u0e48\u0e32\u0e19\u0e31\u0e49\u0e19 \u0e2b\u0e32\u0e01\u0e41\u0e15\u0e48\u0e40\u0e23\u0e35\u0e22\u0e01\u0e27\u0e48\u0e32\u0e04\u0e23\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e0d\u0e35\u0e48\u0e1b\u0e38\u0e48\u0e19\u0e40\u0e25\u0e22\u0e01\u0e47\u0e27\u0e48\u0e32\u0e44\u0e14\u0e49\u00a0 \u0e27\u0e48\u0e32\u0e14\u0e49\u0e27\u0e22\u0e1a\u0e23\u0e23\u0e22\u0e32\u0e01\u0e32\u0e28\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e02\u0e2d\u0e07\u0e23\u0e49\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e23\u0e32\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e27\u0e48\u0e32\u0e2b\u0e25\u0e32\u0e22\u0e04\u0e19\u0e15\u0e49\u0e2d\u0e07\u0e0a\u0e2d\u0e1a\u0e41\u0e19\u0e48\u0e46 \u0e01\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e42\u0e14\u0e14\u0e40\u0e14\u0e48\u0e19\u0e08\u0e32\u0e01\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e44\u0e21\u0e49 \u0e17\u0e31\u0e49\u0e07\u0e44\u0e21\u0e49\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e41\u0e02\u0e47\u0e07 \u0e44\u0e21\u0e48\u0e44\u0e1c\u0e48 \u0e1c\u0e2a\u0e21\u0e1c\u0e2a\u0e32\u0e19\u0e01\u0e31\u0e1a\u0e07\u0e32\u0e19\u0e04\u0e2d\u0e19\u0e01\u0e23\u0e35\u0e15 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e1b\u0e23\u0e31\u0e1a\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e32\u0e21\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e25\u0e14\u0e2b\u0e25\u0e31\u0e48\u0e19\u0e01\u0e31\u0e19\u0e44\u0e1b \u0e0a\u0e31\u0e49\u0e19\u0e25\u0e48\u0e32\u0e07\u0e2a\u0e38\u0e14\u0e40\u0e1b\u0e47\u0e19\u0e0a\u0e38\u0e14\u0e42\u0e15\u0e4a\u0e30\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e17\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e1a\u0e1a\u0e1b\u0e01\u0e15\u0e34 \u0e2a\u0e48\u0e27\u0e19\u0e17\u0e35\u0e48\u0e2a\u0e2d\u0e07\u0e17\u0e33\u0e01\u0e32\u0e23\u0e22\u0e01\u0e1e\u0e37\u0e49\u0e19\u0e2a\u0e39\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e42\u0e15\u0e4a\u0e30\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e17\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e19\u0e31\u0e48\u0e07\u0e1e\u0e37\u0e49\u0e19\u0e2b\u0e49\u0e2d\u0e22\u0e04\u0e32\u0e2a\u0e44\u0e15\u0e25\u0e4c\u0e0d\u0e35\u0e48\u0e1b\u0e38\u0e48\u0e19 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e1a\u0e31\u0e19\u0e44\u0e14\u0e40\u0e25\u0e47\u0e01\u0e46 \u0e44\u0e1b\u0e2a\u0e39\u0e48\u0e0a\u0e31\u0e49\u0e19\u0e25\u0e2d\u0e22 \u0e17\u0e35\u0e48\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e1b\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e49\u0e2d\u0e07\u0e2a\u0e31\u0e07\u0e2a\u0e23\u0e23\u0e04\u0e4c\u0e41\u0e1a\u0e1a\u0e2a\u0e48\u0e27\u0e19\u0e15\u0e31\u0e27\u0e44\u0e14\u0e49 \u0e27\u0e01\u0e01\u0e25\u0e31\u0e1a\u0e40\u0e02\u0e49\u0e32\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e23\u0e32\u0e40\u0e21\u0e19 \u0e40\u0e23\u0e32\u0e02\u0e2d\u0e41\u0e19\u0e30\u0e19\u0e33 Shio Ramen\u00a0\u0e23\u0e32\u0e40\u0e21\u0e19\u0e23\u0e2a\u0e40\u0e01\u0e25\u0e37\u0e2d\u0e17\u0e35\u0e48\u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e40\u0e04\u0e47\u0e21\u0e19\u0e34\u0e14\u0e46 \u0e01\u0e33\u0e25\u0e31\u0e07\u0e14\u0e35 \u0e19\u0e49\u0e33\u0e0b\u0e38\u0e1b\u0e41\u0e21\u0e49\u0e08\u0e30\u0e14\u0e39\u0e43\u0e2a\u0e41\u0e15\u0e48\u0e01\u0e25\u0e31\u0e1a\u0e43\u0e2b\u0e49\u0e23\u0e2a\u0e40\u0e02\u0e49\u0e21\u0e02\u0e49\u0e19\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e25\u0e34\u0e48\u0e19\u0e2b\u0e2d\u0e21\u0e40\u0e2d\u0e32\u0e21\u0e32\u0e01\u0e46 \u0e17\u0e32\u0e07\u0e23\u0e49\u0e32\u0e19\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e43\u0e0a\u0e49\u0e40\u0e2a\u0e49\u0e19\u0e23\u0e32\u0e40\u0e21\u0e19\u0e02\u0e19\u0e32\u0e14\u0e40\u0e25\u0e47\u0e01\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32\u0e08\u0e32\u0e01\u0e0d\u0e35\u0e48\u0e1b\u0e38\u0e48\u0e19 \u0e25\u0e27\u0e01\u0e21\u0e32\u0e41\u0e1a\u0e1a\u0e19\u0e38\u0e48\u0e21\u0e44\u0e21\u0e48\u0e41\u0e02\u0e47\u0e07\u0e21\u0e32\u0e01\u0e19\u0e31\u0e01 \u0e42\u0e1b\u0e30\u0e14\u0e49\u0e27\u0e22\u0e2b\u0e21\u0e39\u0e0a\u0e32\u0e0a\u0e39\u0e15\u0e34\u0e14\u0e21\u0e31\u0e19 \u0e44\u0e02\u0e48\u0e15\u0e49\u0e21\u0e40\u0e15\u0e47\u0e21\u0e1f\u0e2d\u0e07 \u0e40\u0e2b\u0e47\u0e14\u0e2b\u0e39\u0e2b\u0e19\u0e39 \u0e41\u0e25\u0e30\u0e21\u0e30\u0e19\u0e32\u0e27\u0e1d\u0e32\u0e19\u0e1a\u0e32\u0e07\u0e46 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e23\u0e34\u0e01\u0e40\u0e1c\u0e32\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e23\u0e2a\u0e0a\u0e32\u0e15\u0e34 Shio Ramen (180 \u0e1a\u0e32\u0e17) \u0e0a\u0e32\u0e21\u0e15\u0e48\u0e2d\u0e44\u0e1b\u0e40\u0e2d\u0e32\u0e43\u0e08\u0e04\u0e19\u0e23\u0e31\u0e01\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e Tanmen \u0e23\u0e32\u0e40\u0e21\u0e19\u0e1c\u0e31\u0e01\u0e17\u0e35\u0e48\u0e14\u0e39\u0e41\u0e27\u0e4a\u0e1a\u0e41\u0e23\u0e01\u0e04\u0e25\u0e49\u0e32\u0e22\u0e46 \u0e23\u0e32\u0e14\u0e2b\u0e19\u0e49\u0e32\u0e2d\u0e22\u0e39\u0e48\u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e19\u0e01\u0e31\u0e19 \u0e2b\u0e2d\u0e21\u0e01\u0e25\u0e21\u0e01\u0e25\u0e48\u0e2d\u0e21\u0e14\u0e49\u0e27\u0e22\u0e19\u0e49\u0e33\u0e0b\u0e38\u0e1b\u0e42\u0e0a\u0e22\u0e38 \u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21\u0e14\u0e49\u0e27\u0e22\u0e01\u0e25\u0e34\u0e48\u0e19\u0e41\u0e25\u0e30\u0e23\u0e2a\u0e0a\u0e32\u0e15\u0e34\u0e08\u0e32\u0e01\u0e1c\u0e31\u0e01\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e2d\u0e22\u0e48\u0e32\u0e07 \u0e16\u0e31\u0e48\u0e27\u0e07\u0e2d\u0e01 \u0e01\u0e30\u0e2b\u0e25\u0e48\u0e33\u0e1b\u0e25\u0e35 \u0e41\u0e04\u0e23\u0e2d\u0e17 [&hellip;]<\/p>\n","protected":false},"featured_media":4456,"template":"","categories":[26],"tags":[630,631,632,130,55,205],"class_list":["post-4452","restaurant","type-restaurant","status-publish","has-post-thumbnail","hentry","category-recommend","tag-joshoken","tag-nihonmura-mall","tag-uomasa","tag-130","tag-55","tag-205","restaurant-category-casual-dining","restaurant-category-izakaya","restaurant-category-ramen-soba-udon","restaurant-location-thong-lor"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Joshoken - Bangmeshi<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kiji.life\/eats\/restaurant\/joshoken\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Joshoken - Bangmeshi\" \/>\n<meta property=\"og:description\" content=\"Joshoken \u0e01\u0e2d\u0e07\u0e17\u0e31\u0e1e\u0e23\u0e32\u0e40\u0e21\u0e19\u0e1c\u0e39\u0e49\u0e41\u0e02\u0e47\u0e07\u0e41\u0e01\u0e23\u0e48\u0e07 \u0e23\u0e49\u0e32\u0e19\u0e23\u0e32\u0e40\u0e21\u0e19\u0e08\u0e32\u0e01\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e0a\u0e34\u0e1a\u0e30\u0e17\u0e35\u0e48\u0e44\u0e1b\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e0a\u0e37\u0e48\u0e2d\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e42\u0e14\u0e48\u0e07\u0e14\u0e31\u0e07\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e2a\u0e34\u0e07\u0e04\u0e42\u0e1b\u0e23\u0e4c \u0e08\u0e19\u0e02\u0e22\u0e32\u0e22\u0e2a\u0e32\u0e02\u0e32\u0e43\u0e19\u0e2d\u0e35\u0e01\u0e2b\u0e25\u0e32\u0e22\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2a\u0e32\u0e02\u0e32\u0e43\u0e19\u0e44\u0e17\u0e22\u0e40\u0e1e\u0e34\u0e48\u0e07\u0e08\u0e30\u0e42\u0e22\u0e01\u0e22\u0e49\u0e32\u0e22\u0e08\u0e32\u0e01\u0e43\u0e19\u0e0b\u0e2d\u0e22\u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 49 \u0e21\u0e32\u0e2d\u0e22\u0e39\u0e48\u0e17\u0e35\u0e48\u0e15\u0e31\u0e49\u0e07\u0e41\u0e2b\u0e48\u0e07\u0e43\u0e2b\u0e21\u0e48\u0e43\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 Nihonmura Mall \u0e0b\u0e36\u0e48\u0e07\u0e43\u0e0a\u0e49\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e40\u0e14\u0e35\u0e22\u0e27\u0e01\u0e31\u0e19\u0e01\u0e31\u0e1a\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e0d\u0e35\u0e48\u0e1b\u0e38\u0e48\u0e19 Uomasa (\u0e2d\u0e35\u0e01\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e0d\u0e35\u0e48\u0e1b\u0e38\u0e48\u0e19\u0e40\u0e01\u0e48\u0e32\u0e41\u0e01\u0e48\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e41\u0e19\u0e48\u0e19\u0e2d\u0e19\u0e27\u0e48\u0e32\u0e19\u0e31\u0e48\u0e19\u0e08\u0e36\u0e07\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e23\u0e49\u0e32\u0e19 Joshoken \u0e41\u0e2b\u0e48\u0e07\u0e19\u0e35\u0e49 \u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e21\u0e35\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e41\u0e04\u0e48\u0e23\u0e32\u0e40\u0e21\u0e19\u0e40\u0e17\u0e48\u0e32\u0e19\u0e31\u0e49\u0e19 \u0e2b\u0e32\u0e01\u0e41\u0e15\u0e48\u0e40\u0e23\u0e35\u0e22\u0e01\u0e27\u0e48\u0e32\u0e04\u0e23\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e0d\u0e35\u0e48\u0e1b\u0e38\u0e48\u0e19\u0e40\u0e25\u0e22\u0e01\u0e47\u0e27\u0e48\u0e32\u0e44\u0e14\u0e49\u00a0 \u0e27\u0e48\u0e32\u0e14\u0e49\u0e27\u0e22\u0e1a\u0e23\u0e23\u0e22\u0e32\u0e01\u0e32\u0e28\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e02\u0e2d\u0e07\u0e23\u0e49\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e23\u0e32\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e27\u0e48\u0e32\u0e2b\u0e25\u0e32\u0e22\u0e04\u0e19\u0e15\u0e49\u0e2d\u0e07\u0e0a\u0e2d\u0e1a\u0e41\u0e19\u0e48\u0e46 \u0e01\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e42\u0e14\u0e14\u0e40\u0e14\u0e48\u0e19\u0e08\u0e32\u0e01\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e44\u0e21\u0e49 \u0e17\u0e31\u0e49\u0e07\u0e44\u0e21\u0e49\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e41\u0e02\u0e47\u0e07 \u0e44\u0e21\u0e48\u0e44\u0e1c\u0e48 \u0e1c\u0e2a\u0e21\u0e1c\u0e2a\u0e32\u0e19\u0e01\u0e31\u0e1a\u0e07\u0e32\u0e19\u0e04\u0e2d\u0e19\u0e01\u0e23\u0e35\u0e15 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e1b\u0e23\u0e31\u0e1a\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e32\u0e21\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e25\u0e14\u0e2b\u0e25\u0e31\u0e48\u0e19\u0e01\u0e31\u0e19\u0e44\u0e1b \u0e0a\u0e31\u0e49\u0e19\u0e25\u0e48\u0e32\u0e07\u0e2a\u0e38\u0e14\u0e40\u0e1b\u0e47\u0e19\u0e0a\u0e38\u0e14\u0e42\u0e15\u0e4a\u0e30\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e17\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e1a\u0e1a\u0e1b\u0e01\u0e15\u0e34 \u0e2a\u0e48\u0e27\u0e19\u0e17\u0e35\u0e48\u0e2a\u0e2d\u0e07\u0e17\u0e33\u0e01\u0e32\u0e23\u0e22\u0e01\u0e1e\u0e37\u0e49\u0e19\u0e2a\u0e39\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e42\u0e15\u0e4a\u0e30\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e17\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e19\u0e31\u0e48\u0e07\u0e1e\u0e37\u0e49\u0e19\u0e2b\u0e49\u0e2d\u0e22\u0e04\u0e32\u0e2a\u0e44\u0e15\u0e25\u0e4c\u0e0d\u0e35\u0e48\u0e1b\u0e38\u0e48\u0e19 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e1a\u0e31\u0e19\u0e44\u0e14\u0e40\u0e25\u0e47\u0e01\u0e46 \u0e44\u0e1b\u0e2a\u0e39\u0e48\u0e0a\u0e31\u0e49\u0e19\u0e25\u0e2d\u0e22 \u0e17\u0e35\u0e48\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e1b\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e49\u0e2d\u0e07\u0e2a\u0e31\u0e07\u0e2a\u0e23\u0e23\u0e04\u0e4c\u0e41\u0e1a\u0e1a\u0e2a\u0e48\u0e27\u0e19\u0e15\u0e31\u0e27\u0e44\u0e14\u0e49 \u0e27\u0e01\u0e01\u0e25\u0e31\u0e1a\u0e40\u0e02\u0e49\u0e32\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e23\u0e32\u0e40\u0e21\u0e19 \u0e40\u0e23\u0e32\u0e02\u0e2d\u0e41\u0e19\u0e30\u0e19\u0e33 Shio Ramen\u00a0\u0e23\u0e32\u0e40\u0e21\u0e19\u0e23\u0e2a\u0e40\u0e01\u0e25\u0e37\u0e2d\u0e17\u0e35\u0e48\u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e40\u0e04\u0e47\u0e21\u0e19\u0e34\u0e14\u0e46 \u0e01\u0e33\u0e25\u0e31\u0e07\u0e14\u0e35 \u0e19\u0e49\u0e33\u0e0b\u0e38\u0e1b\u0e41\u0e21\u0e49\u0e08\u0e30\u0e14\u0e39\u0e43\u0e2a\u0e41\u0e15\u0e48\u0e01\u0e25\u0e31\u0e1a\u0e43\u0e2b\u0e49\u0e23\u0e2a\u0e40\u0e02\u0e49\u0e21\u0e02\u0e49\u0e19\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e25\u0e34\u0e48\u0e19\u0e2b\u0e2d\u0e21\u0e40\u0e2d\u0e32\u0e21\u0e32\u0e01\u0e46 \u0e17\u0e32\u0e07\u0e23\u0e49\u0e32\u0e19\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e43\u0e0a\u0e49\u0e40\u0e2a\u0e49\u0e19\u0e23\u0e32\u0e40\u0e21\u0e19\u0e02\u0e19\u0e32\u0e14\u0e40\u0e25\u0e47\u0e01\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32\u0e08\u0e32\u0e01\u0e0d\u0e35\u0e48\u0e1b\u0e38\u0e48\u0e19 \u0e25\u0e27\u0e01\u0e21\u0e32\u0e41\u0e1a\u0e1a\u0e19\u0e38\u0e48\u0e21\u0e44\u0e21\u0e48\u0e41\u0e02\u0e47\u0e07\u0e21\u0e32\u0e01\u0e19\u0e31\u0e01 \u0e42\u0e1b\u0e30\u0e14\u0e49\u0e27\u0e22\u0e2b\u0e21\u0e39\u0e0a\u0e32\u0e0a\u0e39\u0e15\u0e34\u0e14\u0e21\u0e31\u0e19 \u0e44\u0e02\u0e48\u0e15\u0e49\u0e21\u0e40\u0e15\u0e47\u0e21\u0e1f\u0e2d\u0e07 \u0e40\u0e2b\u0e47\u0e14\u0e2b\u0e39\u0e2b\u0e19\u0e39 \u0e41\u0e25\u0e30\u0e21\u0e30\u0e19\u0e32\u0e27\u0e1d\u0e32\u0e19\u0e1a\u0e32\u0e07\u0e46 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e23\u0e34\u0e01\u0e40\u0e1c\u0e32\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e23\u0e2a\u0e0a\u0e32\u0e15\u0e34 Shio Ramen (180 \u0e1a\u0e32\u0e17) \u0e0a\u0e32\u0e21\u0e15\u0e48\u0e2d\u0e44\u0e1b\u0e40\u0e2d\u0e32\u0e43\u0e08\u0e04\u0e19\u0e23\u0e31\u0e01\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e Tanmen \u0e23\u0e32\u0e40\u0e21\u0e19\u0e1c\u0e31\u0e01\u0e17\u0e35\u0e48\u0e14\u0e39\u0e41\u0e27\u0e4a\u0e1a\u0e41\u0e23\u0e01\u0e04\u0e25\u0e49\u0e32\u0e22\u0e46 \u0e23\u0e32\u0e14\u0e2b\u0e19\u0e49\u0e32\u0e2d\u0e22\u0e39\u0e48\u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e19\u0e01\u0e31\u0e19 \u0e2b\u0e2d\u0e21\u0e01\u0e25\u0e21\u0e01\u0e25\u0e48\u0e2d\u0e21\u0e14\u0e49\u0e27\u0e22\u0e19\u0e49\u0e33\u0e0b\u0e38\u0e1b\u0e42\u0e0a\u0e22\u0e38 \u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21\u0e14\u0e49\u0e27\u0e22\u0e01\u0e25\u0e34\u0e48\u0e19\u0e41\u0e25\u0e30\u0e23\u0e2a\u0e0a\u0e32\u0e15\u0e34\u0e08\u0e32\u0e01\u0e1c\u0e31\u0e01\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e2d\u0e22\u0e48\u0e32\u0e07 \u0e16\u0e31\u0e48\u0e27\u0e07\u0e2d\u0e01 \u0e01\u0e30\u0e2b\u0e25\u0e48\u0e33\u0e1b\u0e25\u0e35 \u0e41\u0e04\u0e23\u0e2d\u0e17 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kiji.life\/eats\/restaurant\/joshoken\/\" \/>\n<meta property=\"og:site_name\" content=\"Bangmeshi\" \/>\n<meta property=\"article:modified_time\" content=\"2018-08-29T11:06:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/kiji.life\/eats\/wp-content\/uploads\/2018\/08\/FCM_6676-copy.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1279\" \/>\n\t<meta property=\"og:image:height\" content=\"856\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/kiji.life\\\/eats\\\/restaurant\\\/joshoken\\\/\",\"url\":\"https:\\\/\\\/kiji.life\\\/eats\\\/restaurant\\\/joshoken\\\/\",\"name\":\"Joshoken - Bangmeshi\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kiji.life\\\/eats\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/kiji.life\\\/eats\\\/restaurant\\\/joshoken\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/kiji.life\\\/eats\\\/restaurant\\\/joshoken\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/kiji.life\\\/eats\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/FCM_6676-copy.jpg\",\"datePublished\":\"2018-08-29T10:53:55+00:00\",\"dateModified\":\"2018-08-29T11:06:23+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/kiji.life\\\/eats\\\/restaurant\\\/joshoken\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/kiji.life\\\/eats\\\/restaurant\\\/joshoken\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/kiji.life\\\/eats\\\/restaurant\\\/joshoken\\\/#primaryimage\",\"url\":\"https:\\\/\\\/kiji.life\\\/eats\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/FCM_6676-copy.jpg\",\"contentUrl\":\"https:\\\/\\\/kiji.life\\\/eats\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/FCM_6676-copy.jpg\",\"width\":1279,\"height\":856},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/kiji.life\\\/eats\\\/restaurant\\\/joshoken\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/kiji.life\\\/eats\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Restaurants\",\"item\":\"https:\\\/\\\/kiji.life\\\/eats\\\/restaurant\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Joshoken\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/kiji.life\\\/eats\\\/#website\",\"url\":\"https:\\\/\\\/kiji.life\\\/eats\\\/\",\"name\":\"Bangmeshi\",\"description\":\"Bangkok Japanese Restaurant Guide\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/kiji.life\\\/eats\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Joshoken - Bangmeshi","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kiji.life\/eats\/restaurant\/joshoken\/","og_locale":"en_US","og_type":"article","og_title":"Joshoken - Bangmeshi","og_description":"Joshoken \u0e01\u0e2d\u0e07\u0e17\u0e31\u0e1e\u0e23\u0e32\u0e40\u0e21\u0e19\u0e1c\u0e39\u0e49\u0e41\u0e02\u0e47\u0e07\u0e41\u0e01\u0e23\u0e48\u0e07 \u0e23\u0e49\u0e32\u0e19\u0e23\u0e32\u0e40\u0e21\u0e19\u0e08\u0e32\u0e01\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e0a\u0e34\u0e1a\u0e30\u0e17\u0e35\u0e48\u0e44\u0e1b\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e0a\u0e37\u0e48\u0e2d\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e42\u0e14\u0e48\u0e07\u0e14\u0e31\u0e07\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e2a\u0e34\u0e07\u0e04\u0e42\u0e1b\u0e23\u0e4c \u0e08\u0e19\u0e02\u0e22\u0e32\u0e22\u0e2a\u0e32\u0e02\u0e32\u0e43\u0e19\u0e2d\u0e35\u0e01\u0e2b\u0e25\u0e32\u0e22\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2a\u0e32\u0e02\u0e32\u0e43\u0e19\u0e44\u0e17\u0e22\u0e40\u0e1e\u0e34\u0e48\u0e07\u0e08\u0e30\u0e42\u0e22\u0e01\u0e22\u0e49\u0e32\u0e22\u0e08\u0e32\u0e01\u0e43\u0e19\u0e0b\u0e2d\u0e22\u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 49 \u0e21\u0e32\u0e2d\u0e22\u0e39\u0e48\u0e17\u0e35\u0e48\u0e15\u0e31\u0e49\u0e07\u0e41\u0e2b\u0e48\u0e07\u0e43\u0e2b\u0e21\u0e48\u0e43\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 Nihonmura Mall \u0e0b\u0e36\u0e48\u0e07\u0e43\u0e0a\u0e49\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e40\u0e14\u0e35\u0e22\u0e27\u0e01\u0e31\u0e19\u0e01\u0e31\u0e1a\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e0d\u0e35\u0e48\u0e1b\u0e38\u0e48\u0e19 Uomasa (\u0e2d\u0e35\u0e01\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e0d\u0e35\u0e48\u0e1b\u0e38\u0e48\u0e19\u0e40\u0e01\u0e48\u0e32\u0e41\u0e01\u0e48\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e41\u0e19\u0e48\u0e19\u0e2d\u0e19\u0e27\u0e48\u0e32\u0e19\u0e31\u0e48\u0e19\u0e08\u0e36\u0e07\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e23\u0e49\u0e32\u0e19 Joshoken \u0e41\u0e2b\u0e48\u0e07\u0e19\u0e35\u0e49 \u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e21\u0e35\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e41\u0e04\u0e48\u0e23\u0e32\u0e40\u0e21\u0e19\u0e40\u0e17\u0e48\u0e32\u0e19\u0e31\u0e49\u0e19 \u0e2b\u0e32\u0e01\u0e41\u0e15\u0e48\u0e40\u0e23\u0e35\u0e22\u0e01\u0e27\u0e48\u0e32\u0e04\u0e23\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e0d\u0e35\u0e48\u0e1b\u0e38\u0e48\u0e19\u0e40\u0e25\u0e22\u0e01\u0e47\u0e27\u0e48\u0e32\u0e44\u0e14\u0e49\u00a0 \u0e27\u0e48\u0e32\u0e14\u0e49\u0e27\u0e22\u0e1a\u0e23\u0e23\u0e22\u0e32\u0e01\u0e32\u0e28\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e02\u0e2d\u0e07\u0e23\u0e49\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e23\u0e32\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e27\u0e48\u0e32\u0e2b\u0e25\u0e32\u0e22\u0e04\u0e19\u0e15\u0e49\u0e2d\u0e07\u0e0a\u0e2d\u0e1a\u0e41\u0e19\u0e48\u0e46 \u0e01\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e42\u0e14\u0e14\u0e40\u0e14\u0e48\u0e19\u0e08\u0e32\u0e01\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e44\u0e21\u0e49 \u0e17\u0e31\u0e49\u0e07\u0e44\u0e21\u0e49\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e41\u0e02\u0e47\u0e07 \u0e44\u0e21\u0e48\u0e44\u0e1c\u0e48 \u0e1c\u0e2a\u0e21\u0e1c\u0e2a\u0e32\u0e19\u0e01\u0e31\u0e1a\u0e07\u0e32\u0e19\u0e04\u0e2d\u0e19\u0e01\u0e23\u0e35\u0e15 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e1b\u0e23\u0e31\u0e1a\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e32\u0e21\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e25\u0e14\u0e2b\u0e25\u0e31\u0e48\u0e19\u0e01\u0e31\u0e19\u0e44\u0e1b \u0e0a\u0e31\u0e49\u0e19\u0e25\u0e48\u0e32\u0e07\u0e2a\u0e38\u0e14\u0e40\u0e1b\u0e47\u0e19\u0e0a\u0e38\u0e14\u0e42\u0e15\u0e4a\u0e30\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e17\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e1a\u0e1a\u0e1b\u0e01\u0e15\u0e34 \u0e2a\u0e48\u0e27\u0e19\u0e17\u0e35\u0e48\u0e2a\u0e2d\u0e07\u0e17\u0e33\u0e01\u0e32\u0e23\u0e22\u0e01\u0e1e\u0e37\u0e49\u0e19\u0e2a\u0e39\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e42\u0e15\u0e4a\u0e30\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e17\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e19\u0e31\u0e48\u0e07\u0e1e\u0e37\u0e49\u0e19\u0e2b\u0e49\u0e2d\u0e22\u0e04\u0e32\u0e2a\u0e44\u0e15\u0e25\u0e4c\u0e0d\u0e35\u0e48\u0e1b\u0e38\u0e48\u0e19 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e1a\u0e31\u0e19\u0e44\u0e14\u0e40\u0e25\u0e47\u0e01\u0e46 \u0e44\u0e1b\u0e2a\u0e39\u0e48\u0e0a\u0e31\u0e49\u0e19\u0e25\u0e2d\u0e22 \u0e17\u0e35\u0e48\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e1b\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e49\u0e2d\u0e07\u0e2a\u0e31\u0e07\u0e2a\u0e23\u0e23\u0e04\u0e4c\u0e41\u0e1a\u0e1a\u0e2a\u0e48\u0e27\u0e19\u0e15\u0e31\u0e27\u0e44\u0e14\u0e49 \u0e27\u0e01\u0e01\u0e25\u0e31\u0e1a\u0e40\u0e02\u0e49\u0e32\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e23\u0e32\u0e40\u0e21\u0e19 \u0e40\u0e23\u0e32\u0e02\u0e2d\u0e41\u0e19\u0e30\u0e19\u0e33 Shio Ramen\u00a0\u0e23\u0e32\u0e40\u0e21\u0e19\u0e23\u0e2a\u0e40\u0e01\u0e25\u0e37\u0e2d\u0e17\u0e35\u0e48\u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e40\u0e04\u0e47\u0e21\u0e19\u0e34\u0e14\u0e46 \u0e01\u0e33\u0e25\u0e31\u0e07\u0e14\u0e35 \u0e19\u0e49\u0e33\u0e0b\u0e38\u0e1b\u0e41\u0e21\u0e49\u0e08\u0e30\u0e14\u0e39\u0e43\u0e2a\u0e41\u0e15\u0e48\u0e01\u0e25\u0e31\u0e1a\u0e43\u0e2b\u0e49\u0e23\u0e2a\u0e40\u0e02\u0e49\u0e21\u0e02\u0e49\u0e19\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e25\u0e34\u0e48\u0e19\u0e2b\u0e2d\u0e21\u0e40\u0e2d\u0e32\u0e21\u0e32\u0e01\u0e46 \u0e17\u0e32\u0e07\u0e23\u0e49\u0e32\u0e19\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e43\u0e0a\u0e49\u0e40\u0e2a\u0e49\u0e19\u0e23\u0e32\u0e40\u0e21\u0e19\u0e02\u0e19\u0e32\u0e14\u0e40\u0e25\u0e47\u0e01\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32\u0e08\u0e32\u0e01\u0e0d\u0e35\u0e48\u0e1b\u0e38\u0e48\u0e19 \u0e25\u0e27\u0e01\u0e21\u0e32\u0e41\u0e1a\u0e1a\u0e19\u0e38\u0e48\u0e21\u0e44\u0e21\u0e48\u0e41\u0e02\u0e47\u0e07\u0e21\u0e32\u0e01\u0e19\u0e31\u0e01 \u0e42\u0e1b\u0e30\u0e14\u0e49\u0e27\u0e22\u0e2b\u0e21\u0e39\u0e0a\u0e32\u0e0a\u0e39\u0e15\u0e34\u0e14\u0e21\u0e31\u0e19 \u0e44\u0e02\u0e48\u0e15\u0e49\u0e21\u0e40\u0e15\u0e47\u0e21\u0e1f\u0e2d\u0e07 \u0e40\u0e2b\u0e47\u0e14\u0e2b\u0e39\u0e2b\u0e19\u0e39 \u0e41\u0e25\u0e30\u0e21\u0e30\u0e19\u0e32\u0e27\u0e1d\u0e32\u0e19\u0e1a\u0e32\u0e07\u0e46 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e23\u0e34\u0e01\u0e40\u0e1c\u0e32\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e23\u0e2a\u0e0a\u0e32\u0e15\u0e34 Shio Ramen (180 \u0e1a\u0e32\u0e17) \u0e0a\u0e32\u0e21\u0e15\u0e48\u0e2d\u0e44\u0e1b\u0e40\u0e2d\u0e32\u0e43\u0e08\u0e04\u0e19\u0e23\u0e31\u0e01\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e Tanmen \u0e23\u0e32\u0e40\u0e21\u0e19\u0e1c\u0e31\u0e01\u0e17\u0e35\u0e48\u0e14\u0e39\u0e41\u0e27\u0e4a\u0e1a\u0e41\u0e23\u0e01\u0e04\u0e25\u0e49\u0e32\u0e22\u0e46 \u0e23\u0e32\u0e14\u0e2b\u0e19\u0e49\u0e32\u0e2d\u0e22\u0e39\u0e48\u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e19\u0e01\u0e31\u0e19 \u0e2b\u0e2d\u0e21\u0e01\u0e25\u0e21\u0e01\u0e25\u0e48\u0e2d\u0e21\u0e14\u0e49\u0e27\u0e22\u0e19\u0e49\u0e33\u0e0b\u0e38\u0e1b\u0e42\u0e0a\u0e22\u0e38 \u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21\u0e14\u0e49\u0e27\u0e22\u0e01\u0e25\u0e34\u0e48\u0e19\u0e41\u0e25\u0e30\u0e23\u0e2a\u0e0a\u0e32\u0e15\u0e34\u0e08\u0e32\u0e01\u0e1c\u0e31\u0e01\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e2d\u0e22\u0e48\u0e32\u0e07 \u0e16\u0e31\u0e48\u0e27\u0e07\u0e2d\u0e01 \u0e01\u0e30\u0e2b\u0e25\u0e48\u0e33\u0e1b\u0e25\u0e35 \u0e41\u0e04\u0e23\u0e2d\u0e17 [&hellip;]","og_url":"https:\/\/kiji.life\/eats\/restaurant\/joshoken\/","og_site_name":"Bangmeshi","article_modified_time":"2018-08-29T11:06:23+00:00","og_image":[{"width":1279,"height":856,"url":"https:\/\/kiji.life\/eats\/wp-content\/uploads\/2018\/08\/FCM_6676-copy.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/kiji.life\/eats\/restaurant\/joshoken\/","url":"https:\/\/kiji.life\/eats\/restaurant\/joshoken\/","name":"Joshoken - Bangmeshi","isPartOf":{"@id":"https:\/\/kiji.life\/eats\/#website"},"primaryImageOfPage":{"@id":"https:\/\/kiji.life\/eats\/restaurant\/joshoken\/#primaryimage"},"image":{"@id":"https:\/\/kiji.life\/eats\/restaurant\/joshoken\/#primaryimage"},"thumbnailUrl":"https:\/\/kiji.life\/eats\/wp-content\/uploads\/2018\/08\/FCM_6676-copy.jpg","datePublished":"2018-08-29T10:53:55+00:00","dateModified":"2018-08-29T11:06:23+00:00","breadcrumb":{"@id":"https:\/\/kiji.life\/eats\/restaurant\/joshoken\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kiji.life\/eats\/restaurant\/joshoken\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/kiji.life\/eats\/restaurant\/joshoken\/#primaryimage","url":"https:\/\/kiji.life\/eats\/wp-content\/uploads\/2018\/08\/FCM_6676-copy.jpg","contentUrl":"https:\/\/kiji.life\/eats\/wp-content\/uploads\/2018\/08\/FCM_6676-copy.jpg","width":1279,"height":856},{"@type":"BreadcrumbList","@id":"https:\/\/kiji.life\/eats\/restaurant\/joshoken\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/kiji.life\/eats\/"},{"@type":"ListItem","position":2,"name":"Restaurants","item":"https:\/\/kiji.life\/eats\/restaurant\/"},{"@type":"ListItem","position":3,"name":"Joshoken"}]},{"@type":"WebSite","@id":"https:\/\/kiji.life\/eats\/#website","url":"https:\/\/kiji.life\/eats\/","name":"Bangmeshi","description":"Bangkok Japanese Restaurant Guide","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kiji.life\/eats\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/kiji.life\/eats\/wp-json\/wp\/v2\/restaurant\/4452","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kiji.life\/eats\/wp-json\/wp\/v2\/restaurant"}],"about":[{"href":"https:\/\/kiji.life\/eats\/wp-json\/wp\/v2\/types\/restaurant"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kiji.life\/eats\/wp-json\/wp\/v2\/media\/4456"}],"wp:attachment":[{"href":"https:\/\/kiji.life\/eats\/wp-json\/wp\/v2\/media?parent=4452"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/kiji.life\/eats\/wp-json\/wp\/v2\/categories?post=4452"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/kiji.life\/eats\/wp-json\/wp\/v2\/tags?post=4452"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}